{"id":3273,"count":19,"description":"","link":"https:\/\/antidotmedia.noblogs.org\/nl\/post\/category\/violences-policieres\/police-politique\/","name":"Police politique","slug":"police-politique","taxonomy":"category","parent":1,"meta":[],"_links":{"self":[{"href":"https:\/\/antidotmedia.noblogs.org\/wp-json\/wp\/v2\/categories\/3273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/antidotmedia.noblogs.org\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/antidotmedia.noblogs.org\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/antidotmedia.noblogs.org\/wp-json\/wp\/v2\/categories\/1"}],"wp:post_type":[{"href":"https:\/\/antidotmedia.noblogs.org\/wp-json\/wp\/v2\/posts?categories=3273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}